{"id":1837,"date":"2025-07-03T04:27:13","date_gmt":"2025-07-03T04:27:13","guid":{"rendered":"https:\/\/www.coinspeaker.com\/fr\/?p=1837"},"modified":"2025-07-03T12:49:25","modified_gmt":"2025-07-03T12:49:25","slug":"80-commercants-adoptent-binance-pay","status":"publish","type":"post","link":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/","title":{"rendered":"Plus de 80 commer\u00e7ants de la C\u00f4te d&rsquo;Azur adoptent Binance Pay"},"content":{"rendered":"<h2>Le partenariat entre Binance Pay et la soci\u00e9t\u00e9 de tech financi\u00e8re<\/h2>\n<p>Binance Pay s&rsquo;est associ\u00e9 \u00e0 Lyzi afin de principalement <strong>convaincre les entreprises de la C\u00f4te d&rsquo;Azur d\u2019adopter les transactions avec cryptomonnaies<\/strong>.<\/p>\n<p>Le d\u00e9ploiement inclut des villes comme Nice, Cannes, Monaco et Antibes. La C\u00f4te d&rsquo;Azur est une destination touristique extr\u00eamement pris\u00e9e. Donc, l\u2019int\u00e9gration des actifs num\u00e9riques sert \u00e0 <strong>booster le commerce de d\u00e9tail et l&rsquo;\u00e9conomie du tourisme de luxe<\/strong>.<\/p>\n<p>Le partenariat offre aux int\u00e9ress\u00e9s la possibilit\u00e9 d\u2019utiliser des stablecoins ou plusieurs types de cryptomonnaies dans de <strong>nombreux \u00e9tablissements<\/strong>.<\/p>\n<p>Cette initiative est un signe de la normalit\u00e9 des <a href=\"https:\/\/www.coinspeaker.com\/fr\/guides\/nouvelle-crypto-binance\/\">cryptos<\/a>. Vu que les paiements en cryptomonnaies sont adopt\u00e9s en C\u00f4te d&rsquo;Azur indique que <strong>la monnaie num\u00e9rique n&rsquo;est plus un concept<\/strong>.<\/p>\n<p>En scannant un code QR et en confirmant une transaction, les clients peuvent r\u00e9gler leurs factures instantan\u00e9ment <strong>sans frais de gaz<\/strong>.<\/p>\n<p>Parall\u00e8lement, les commer\u00e7ants b\u00e9n\u00e9ficient d&rsquo;un <strong>r\u00e8glement imm\u00e9diat en euros<\/strong> gr\u00e2ce \u00e0 l&rsquo;int\u00e9gration du syst\u00e8me.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/OgC4_Gcppzg?si=vwmVn2iUQdsWqrwk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Le projet pourrait inciter d&rsquo;autres villes \u00e0 accepter les cryptomonnaies<\/h2>\n<p>Au d\u00e9but de l&rsquo;ann\u00e9e, Binance Pay a franchi une \u00e9tape importante en Europe. En f\u00e9vrier, il a conclu un partenariat avec <a rel=\"noopener noreferrer\" href=\"https:\/\/www.xmoney.com\/\" target=\"_blank\">xMoney,<\/a> une importante <strong>soci\u00e9t\u00e9 de paiement travaillant avec des entreprises Web3<\/strong>.<\/p>\n<p>Cet accord a permis de <strong>relier Binance Pay \u00e0 de nombreuses autres entreprises<\/strong> en Europe. \u00c0 cela s&rsquo;ajoute l&rsquo;accord avec Lyzi, qui attire encore plus d&rsquo;entreprises sur le r\u00e9seau.<\/p>\n<p>La s\u00e9curit\u00e9 des utilisateurs est importante. De ce fait, Binance Pay a mis en place des <strong>mesures de s\u00e9curit\u00e9 solides<\/strong> pour ses clients.<\/p>\n<p>La plateforme propose aussi des options de <strong>s\u00e9curit\u00e9 pour les transferts et la v\u00e9rification \u00e0 deux facteurs<\/strong>. Pour continuer, la confirmation des compensations est instantan\u00e9e et le processus de paiement est rapide.<\/p>\n<p>Binance Pay vise \u00e0 <strong>simplifier les d\u00e9penses en cryptomonnaies<\/strong> pour tout le monde. Une grande partie de la population poss\u00e8de des cryptomonnaies, mais ne les utilise pas n\u00e9cessairement.<\/p>\n<p>Ce projet vise \u00e0 changer cela. En montrant aux particuliers qu&rsquo;ils peuvent utiliser les cryptomonnaies pour leurs achats quotidiens, <strong>Binance Pay souhaite \u00e9voluer<\/strong>. Il veut familiariser davantage de citoyens avec la monnaie num\u00e9rique.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"474\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\ude80\u00a0This summer, Cannes becomes the crypto capital with Lyzi!<\/p>\n<p>From June 28 to July 6, pay in crypto across 80+ shops in <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/twitter.com\/hashtag\/Cannes?src=hash&amp;ref_src=twsrc%5Etfw\">#Cannes<\/a>, a project led by Lyzi and supported by the city\u2019s mayor <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/twitter.com\/davidlisnard?ref_src=twsrc%5Etfw\">@davidlisnard<\/a>.<\/p>\n<p>\ud83e\udd1d\u00a0With <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/twitter.com\/binance?ref_src=twsrc%5Etfw\">@Binance<\/a> Pay and <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/twitter.com\/BankingCircle?ref_src=twsrc%5Etfw\">@BankingCircle<\/a>  onboard:<\/p>\n<p>&#8211; Spend \u20ac20+ in crypto, get\u2026 <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/t.co\/uZd3mHTWYw\">pic.twitter.com\/uZd3mHTWYw<\/a><\/p>\n<p>&mdash; Lyzi \ud83c\uddeb\ud83c\uddf7 (@Lyzi_app) <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/twitter.com\/Lyzi_app\/status\/1938989181256044730?ref_src=twsrc%5Etfw\">June 28, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>La C\u00f4te d&rsquo;Azur n&rsquo;est qu&rsquo;un d\u00e9but<\/h2>\n<p>D&rsquo;autres villes et des <a rel=\"noopener noreferrer\" href=\"https:\/\/www.binance.com\/fr\/blog\/payments\/%F0%9F%8F%9D%EF%B8%8F-la-french-riviera--la-liste-compl%C3%A8te-des-commer%C3%A7ants-acceptant-binance-pay-7019380802531337118\" target=\"_blank\">entreprises<\/a> suivront ce projet s&rsquo;il est couronn\u00e9 de succ\u00e8s.<\/p>\n<p>En attendant, cela signifie que <strong>les touristes qui viennent \u00e0 Cannes ou \u00e0 Nice peuvent facilement d\u00e9penser leurs cryptomonnaies<\/strong>. Ils passeront leur \u00e9t\u00e9 et auront l&rsquo;occasion de voir comment les cryptomonnaies fonctionnent dans la vie quotidienne.<\/p>\n<p>Enfin, les d\u00e9penses en cryptomonnaies ne se font <strong>plus uniquement sur Internet<\/strong>. Aujourd&rsquo;hui, elles se font aussi sur les plages europ\u00e9ennes par beau temps et m\u00eame dans les rues bond\u00e9es.<\/p>\n<p>Binance Pay et Lyzi souhaitent s&rsquo;assurer que chacun puisse <strong>utiliser les cryptomonnaies comme de l&rsquo;argent<\/strong>.<\/p>\n<p>Bient\u00f4t, ils ajouteront peut-\u00eatre les nouveaux meme coins qui font une bonne performance tels que <a rel=\"nofollow sponsored\" href=\"https:\/\/www.coinspeaker.com\/fr\/go\/snorter\" target=\"_blank\">Snorter<\/a> dans leur liste.<\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\"><a href=\"https:\/\/www.coinspeaker.com\/fr\/go\/snorter\" rel=\"noopener sponsored nofollow\" target=\"_blank\" class=\"custom-cta-button\">D\u00e9couvrez Snorter ($SNORT)<\/a><\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"474\" data-dnt=\"true\">\n<p lang=\"fr\" dir=\"ltr\">La crypto s\u2019invite sur la C\u00f4te d\u2019Azur <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/t.co\/NwygBa0zyg\">https:\/\/t.co\/NwygBa0zyg<\/a><\/p>\n<p>&mdash; BeInCrypto \ud83c\uddeb\ud83c\uddf7 (@BeInCrypto_fr) <a rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener nofollow sponsored\" href=\"https:\/\/twitter.com\/BeInCrypto_fr\/status\/1940411101201461741?ref_src=twsrc%5Etfw\">July 2, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<hr \/>\n<p>Source : <a rel=\"noopener noreferrer\" href=\"https:\/\/www.ainvest.com\/news\/binance-pay-partners-lyzi-revolutionize-crypto-payments-french-riviera-2507\/\" target=\"_blank\">AInvest<\/a><\/p>\n<p>\u00c0 lire aussi :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.coinspeaker.com\/fr\/juillet-acheter-ces-altcoins-x10-avant-nouvel-ath-bitcoin\/\">Juillet est le dernier mois pour acheter ces altcoins x10 avant nouvel ATH du Bitcoin<\/a><\/li>\n<li><a href=\"https:\/\/www.coinspeaker.com\/fr\/kinexys-credits-carbone\/\">Kinexys : bient\u00f4t au coeur des cr\u00e9dits carbone ?<\/a><\/li>\n<\/ul>\n<hr \/>\n<p class=\"disclaimer-rw\" style=\"text-align: center\"><em>Cet article ne repr\u00e9sente en aucun cas un conseil en investissement. Veuillez faire vos propres recherches et \u00eatre conscients qu&rsquo;investir comporte des risques. Aussi, certains liens d&rsquo;affiliation se trouvent sur cette page et nous g\u00e9n\u00e8rent de l&rsquo;argent.<\/em><\/p>\n<a class=\"infinscroll_next_page_link\" style=\"display:none\" href=\"https:\/\/www.coinspeaker.com\/fr\/chatgpt-connait-prix-xrp-pepe-shiba-inu-fin-2025\/\" rel=\"prev\">next<\/a>","protected":false},"excerpt":{"rendered":"<p>L\u2019adoption des cryptomonnaies a atteint la C\u00f4te d&rsquo;Azur \u00e0 la suite d&rsquo;un partenariat entre Binance Pay et Lyzi.<\/p>\n<p>Plus de 80 commer\u00e7ants de la r\u00e9gion acceptent d\u00e9sormais les paiements en stablecoins et en cryptomonnaies.<\/p>\n","protected":false},"author":220,"featured_media":1840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,41],"tags":[],"class_list":["post-1837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu","category-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plus de 80 commer\u00e7ants de la C\u00f4te d&#039;Azur adoptent Binance Pay<\/title>\n<meta name=\"description\" content=\"L&#039;adoption des cryptomonnaies a atteint la r\u00e9gion de la C\u00f4te d&#039;Azur suite \u00e0 un partenariat entre Binance Pay et Lyzi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de 80 commer\u00e7ants de la C\u00f4te d&#039;Azur adoptent Binance Pay\" \/>\n<meta property=\"og:description\" content=\"L&#039;adoption des cryptomonnaies a atteint la r\u00e9gion de la C\u00f4te d&#039;Azur suite \u00e0 un partenariat entre Binance Pay et Lyzi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/\" \/>\n<meta property=\"og:site_name\" content=\"Coinspeaker France\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-03T04:27:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T12:49:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/Coinspeaker_5_optimized_1000.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1881\" \/>\n\t<meta property=\"og:image:height\" content=\"1254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emmanuel Roux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emmanuel Roux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus de 80 commer\u00e7ants de la C\u00f4te d'Azur adoptent Binance Pay","description":"L'adoption des cryptomonnaies a atteint la r\u00e9gion de la C\u00f4te d'Azur suite \u00e0 un partenariat entre Binance Pay et Lyzi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de 80 commer\u00e7ants de la C\u00f4te d'Azur adoptent Binance Pay","og_description":"L'adoption des cryptomonnaies a atteint la r\u00e9gion de la C\u00f4te d'Azur suite \u00e0 un partenariat entre Binance Pay et Lyzi.","og_url":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/","og_site_name":"Coinspeaker France","article_published_time":"2025-07-03T04:27:13+00:00","article_modified_time":"2025-07-03T12:49:25+00:00","og_image":[{"width":1881,"height":1254,"url":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/Coinspeaker_5_optimized_1000.png","type":"image\/png"}],"author":"Emmanuel Roux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Emmanuel Roux","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#article","isPartOf":{"@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/"},"author":{"name":"Emmanuel Roux","@id":"https:\/\/www.coinspeaker.com\/fr\/#\/schema\/person\/8756dd8dfcdf8c99f3610ff910bde29f"},"headline":"Plus de 80 commer\u00e7ants de la C\u00f4te d&rsquo;Azur adoptent Binance Pay","datePublished":"2025-07-03T04:27:13+00:00","dateModified":"2025-07-03T12:49:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/"},"wordCount":639,"commentCount":0,"image":{"@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/Coinspeaker_5_optimized_1000.png","articleSection":["Actualit\u00e9s","France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.coinspeaker.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/","url":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/","name":"Plus de 80 commer\u00e7ants de la C\u00f4te d'Azur adoptent Binance Pay","isPartOf":{"@id":"https:\/\/www.coinspeaker.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#primaryimage"},"image":{"@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/Coinspeaker_5_optimized_1000.png","datePublished":"2025-07-03T04:27:13+00:00","dateModified":"2025-07-03T12:49:25+00:00","author":{"@id":"https:\/\/www.coinspeaker.com\/fr\/#\/schema\/person\/8756dd8dfcdf8c99f3610ff910bde29f"},"description":"L'adoption des cryptomonnaies a atteint la r\u00e9gion de la C\u00f4te d'Azur suite \u00e0 un partenariat entre Binance Pay et Lyzi.","breadcrumb":{"@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#primaryimage","url":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/Coinspeaker_5_optimized_1000.png","contentUrl":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/07\/Coinspeaker_5_optimized_1000.png","width":1881,"height":1254,"caption":"80+ commer\u00e7ants de la C\u00f4te d'Azur adoptent Binance Pay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coinspeaker.com\/fr\/80-commercants-adoptent-binance-pay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.coinspeaker.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Plus de 80 commer\u00e7ants de la C\u00f4te d&rsquo;Azur adoptent Binance Pay"}]},{"@type":"WebSite","@id":"https:\/\/www.coinspeaker.com\/fr\/#website","url":"https:\/\/www.coinspeaker.com\/fr\/","name":"Coinspeaker France","description":"Bitcoin, Ethereum, Altcoins et actualit\u00e9s crypto avec analyses, cours en direct, graphiques de donn\u00e9es et guides","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coinspeaker.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.coinspeaker.com\/fr\/#\/schema\/person\/8756dd8dfcdf8c99f3610ff910bde29f","name":"Emmanuel Roux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/cropped-cropped-pp-1-96x96.png","url":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/cropped-cropped-pp-1-96x96.png","contentUrl":"https:\/\/www.coinspeaker.com\/fr\/wp-content\/uploads\/sites\/6\/2025\/06\/cropped-cropped-pp-1-96x96.png","caption":"Emmanuel Roux"},"description":"Journaliste sp\u00e9cialis\u00e9 crypto et Web3, Emmanuel d\u00e9crypte l\u2019actualit\u00e9 des march\u00e9s, des projets blockchain et des grandes tendances du num\u00e9rique.","url":"https:\/\/www.coinspeaker.com\/fr\/author\/desireemeunier\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/posts\/1837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/users\/220"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/comments?post=1837"}],"version-history":[{"count":4,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/posts\/1837\/revisions"}],"predecessor-version":[{"id":1884,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/posts\/1837\/revisions\/1884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/media\/1840"}],"wp:attachment":[{"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/media?parent=1837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/categories?post=1837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coinspeaker.com\/fr\/wp-json\/wp\/v2\/tags?post=1837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}