{"id":1514,"date":"2025-06-27T12:08:51","date_gmt":"2025-06-27T12:08:51","guid":{"rendered":"https:\/\/www.coinspeaker.com\/pt\/?p=1514"},"modified":"2025-06-27T12:29:12","modified_gmt":"2025-06-27T12:29:12","slug":"ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo","status":"publish","type":"post","link":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/","title":{"rendered":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo"},"content":{"rendered":"<p><b>Resumo da not\u00edcia:<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Paolo Ardoino afirma que empresa ser\u00e1 a maior mineradora de Bitcoin at\u00e9 o final de 2025.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Tether j\u00e1 investiu mais de US$ 2 bilh\u00f5es em energia e minera\u00e7\u00e3o na Am\u00e9rica Latina.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Emissora do USDT pretende integrar minera\u00e7\u00e3o \u00e0 estrat\u00e9gia de \u2018energia est\u00e1vel\u2019.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">A Tether, conhecida por emitir a stablecoin USDT, pretende se tornar a maior mineradora de Bitcoin do mundo este ano. A meta foi revelada por Paolo Ardoino, CEO da empresa, em entrevista ao podcast The Big Brain.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Segundo ele, a estrat\u00e9gia de minera\u00e7\u00e3o protege os mais de 100.000 BTC que fazem parte do patrim\u00f4nio da companhia.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, Ardoino afirmou que a compra direta de BTC costuma ser mais lucrativa que a minera\u00e7\u00e3o:<\/span><\/p>\n<blockquote><p>Voc\u00ea sempre ganhar\u00e1 mais dinheiro comprando BTC diretamente.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">No entanto, para empresas com grande exposi\u00e7\u00e3o \u00e0 criptomoeda, participar da seguran\u00e7a da rede se torna tamb\u00e9m estrat\u00e9gico.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Tether aposta em quatro pilares para o futuro<\/span><\/h2>\n<p><span style=\"font-weight: 400\">A minera\u00e7\u00e3o \u00e9 parte de uma vis\u00e3o mais ampla da Tether, chamada de \u2018energia est\u00e1vel\u2019. O conceito integra uma agenda com quatro pilares: dinheiro est\u00e1vel, energia, comunica\u00e7\u00e3o e intelig\u00eancia. A ideia \u00e9 garantir maior resili\u00eancia social no longo prazo.<\/span><\/p>\n<p><b>Quer saber onde est\u00e3o as melhores alternativas de investimento cripto? Leia tamb\u00e9m:<\/b> <a href=\"https:\/\/www.coinspeaker.com\/pt\/melhores-criptomoedas-para-investir\/\" target=\"_blank\"><span style=\"font-weight: 400\">Melhores Criptomoedas Para Investir em Junho de 2025<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Tamb\u00e9m chama aten\u00e7\u00e3o o investimento da empresa em infraestrutura. A Tether aplicou mais de US$ 2 bilh\u00f5es em projetos de energia e minera\u00e7\u00e3o em 15 locais da Am\u00e9rica Latina. Entre os pa\u00edses, est\u00e3o Uruguai, Paraguai e El Salvador.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os aportes incluem usinas renov\u00e1veis, constru\u00e7\u00e3o de subesta\u00e7\u00f5es e participa\u00e7\u00e3o em fazendas j\u00e1 operacionais. No entanto, a empresa ainda n\u00e3o divulgou seu hashrate atual, o que dificulta comparar sua capacidade com a de concorrentes.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Isso ocorre em um momento no qual analistas questionam a capacidade da Tether de manter sua lideran\u00e7a em stablecoins. Afinal, com a <\/span><a href=\"https:\/\/www.coinspeaker.com\/pt\/senado-dos-eua-aprova-o-genius-act-lei-impulsiona-stablecoins\/\" target=\"_blank\"><span style=\"font-weight: 400\">aprova\u00e7\u00e3o do GENIUS Act nos EUA<\/span><\/a><span style=\"font-weight: 400\">, a emissora do USDT j\u00e1 se prepara para mudan\u00e7as.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Concorr\u00eancia com gigantes do setor<\/span><\/h2>\n<p><span style=\"font-weight: 400\">As maiores mineradoras por hashrate incluem a MARA, com 57,3 EH\/s, e a CleanSpark, com 50 EH\/s. Em seguida v\u00eam a IREN, a Riot Platforms e a Core Scientific. O total da rede gira em torno de 810 EH\/s.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ent\u00e3o, para alcan\u00e7ar o topo, a Tether ter\u00e1 que competir com empresas que t\u00eam anos de experi\u00eancia e estruturas consolidadas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No entanto, esfor\u00e7o para isso n\u00e3o falta. A empresa comprou US$ 32 milh\u00f5es em a\u00e7\u00f5es da Bitdeer, da qual j\u00e1 detinha 25%. Portanto, a movimenta\u00e7\u00e3o refor\u00e7a a ambi\u00e7\u00e3o da Tether de escalar rapidamente sua atua\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A meta declarada por Ardoino soa ousada. Mas, considerando os recursos da empresa e a poss\u00edvel <\/span><a rel=\"noopener noreferrer\" href=\"https:\/\/www.coindesk.com\/markets\/2025\/06\/24\/bitcoin-set-for-biggest-mining-difficulty-drop-since-july-2021\" target=\"_blank\"><span style=\"font-weight: 400\">queda da dificuldade de minera\u00e7\u00e3o<\/span><\/a><span style=\"font-weight: 400\">, pode ser algo vi\u00e1vel.<\/span><\/p>\n<p><b><i>Disclaimer: Coinspeaker est\u00e1 comprometido em fornecer reportagens imparciais e transparentes. Este artigo tem como objetivo fornecer informa\u00e7\u00f5es precisas e oportunas. Mas n\u00e3o deve ser considerado como conselho financeiro ou de investimento. Como as condi\u00e7\u00f5es do mercado podem mudar rapidamente, recomendamos que voc\u00ea verifique as informa\u00e7\u00f5es por conta pr\u00f3pria. E consulte um profissional antes de tomar qualquer decis\u00e3o com base neste conte\u00fado.<\/i><\/b><\/p>\n<a class=\"infinscroll_next_page_link\" style=\"display:none\" href=\"https:\/\/www.coinspeaker.com\/pt\/entidade-ve-uso-maior-de-stablecoins-em-atividades-criminosas\/\" rel=\"prev\">next<\/a>","protected":false},"excerpt":{"rendered":"<p>A meta foi revelada por Paolo Ardoino, CEO da empresa, em entrevista ao podcast The Big Brain.<\/p>\n","protected":false},"author":157,"featured_media":1161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[188,242,105],"class_list":["post-1514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-criptomoedas","tag-mineracao-de-bitcoin","tag-tether","tag-usdt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas<\/title>\n<meta name=\"description\" content=\"Entenda por que a Tether, conhecida por emitir a stablecoin USDT, pretende se tornar a maior mineradora de Bitcoin do mundo este ano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas\" \/>\n<meta property=\"og:description\" content=\"Entenda por que a Tether, conhecida por emitir a stablecoin USDT, pretende se tornar a maior mineradora de Bitcoin do mundo este ano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T12:08:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T12:29:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/mineracao-de-bitcoin-na-franca.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flavio Aguilar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavio Aguilar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","description":"Entenda por que a Tether, conhecida por emitir a stablecoin USDT, pretende se tornar a maior mineradora de Bitcoin do mundo este ano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/","og_locale":"pt_PT","og_type":"article","og_title":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","og_description":"Entenda por que a Tether, conhecida por emitir a stablecoin USDT, pretende se tornar a maior mineradora de Bitcoin do mundo este ano.","og_url":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/","og_site_name":"Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","article_published_time":"2025-06-27T12:08:51+00:00","article_modified_time":"2025-06-27T12:29:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/mineracao-de-bitcoin-na-franca.png","type":"image\/png"}],"author":"Flavio Aguilar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Flavio Aguilar","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#article","isPartOf":{"@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/"},"author":{"name":"Flavio Aguilar","@id":"https:\/\/www.coinspeaker.com\/pt\/#\/schema\/person\/2a37f3952c180d28cd90ba1e1070f130"},"headline":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo","datePublished":"2025-06-27T12:08:51+00:00","dateModified":"2025-06-27T12:29:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/"},"wordCount":568,"commentCount":0,"image":{"@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/mineracao-de-bitcoin-na-franca.png","keywords":["Minera\u00e7\u00e3o de Bitcoin","Tether","USDT"],"articleSection":["Not\u00edcias de Criptomoedas"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.coinspeaker.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/","url":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/","name":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","isPartOf":{"@id":"https:\/\/www.coinspeaker.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#primaryimage"},"image":{"@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/mineracao-de-bitcoin-na-franca.png","datePublished":"2025-06-27T12:08:51+00:00","dateModified":"2025-06-27T12:29:12+00:00","author":{"@id":"https:\/\/www.coinspeaker.com\/pt\/#\/schema\/person\/2a37f3952c180d28cd90ba1e1070f130"},"description":"Entenda por que a Tether, conhecida por emitir a stablecoin USDT, pretende se tornar a maior mineradora de Bitcoin do mundo este ano.","breadcrumb":{"@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#primaryimage","url":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/mineracao-de-bitcoin-na-franca.png","contentUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/mineracao-de-bitcoin-na-franca.png","width":1200,"height":800,"caption":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coinspeaker.com\/pt\/ceo-afirma-que-tether-sera-maior-mineradora-de-bitcoin-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.coinspeaker.com\/pt\/"},{"@type":"ListItem","position":2,"name":"CEO afirma que Tether ser\u00e1 maior mineradora de Bitcoin do mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.coinspeaker.com\/pt\/#website","url":"https:\/\/www.coinspeaker.com\/pt\/","name":"Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","description":"Not\u00edcias de criptomoedas em tempo real! \u00daltimas tend\u00eancias e acontecimentos da blockchain, Bitcoin, Ethereum e Altcoins.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coinspeaker.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.coinspeaker.com\/pt\/#\/schema\/person\/2a37f3952c180d28cd90ba1e1070f130","name":"Flavio Aguilar","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/cropped-70B0FA23-7C59-48F4-B3AC-4788A45D299F-96x96.jpg","url":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/cropped-70B0FA23-7C59-48F4-B3AC-4788A45D299F-96x96.jpg","contentUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/cropped-70B0FA23-7C59-48F4-B3AC-4788A45D299F-96x96.jpg","caption":"Flavio Aguilar"},"description":"Flavio Aguilar \u00e9 jornalista e economista formado pela Universidade Federal do Rio Grande do Sul (UFRGS). Atua h\u00e1 mais de 15 anos como rep\u00f3rter e editor em jornais e portais de not\u00edcias no Brasil. No momento, est\u00e1 cursando o mestrado em estudos liter\u00e1rios da Universidade do Porto.","url":"https:\/\/www.coinspeaker.com\/pt\/author\/flavio\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts\/1514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/users\/157"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/comments?post=1514"}],"version-history":[{"count":3,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts\/1514\/revisions"}],"predecessor-version":[{"id":1522,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts\/1514\/revisions\/1522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/media\/1161"}],"wp:attachment":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/media?parent=1514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/categories?post=1514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/tags?post=1514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}