{"id":3287,"date":"2025-08-15T21:20:04","date_gmt":"2025-08-15T21:20:04","guid":{"rendered":"https:\/\/www.coinspeaker.com\/pt\/?p=3287"},"modified":"2025-08-15T18:34:32","modified_gmt":"2025-08-15T18:34:32","slug":"kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral","status":"publish","type":"post","link":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/","title":{"rendered":"KuCoin e AlloyX avan\u00e7am na integra\u00e7\u00e3o de RWAs com teste de colateral"},"content":{"rendered":"<p>A KuCoin e a AlloyX anunciaram um programa-piloto para integrar tokens de ativos do mundo real (RWAs) aos mecanismos de colateral da exchange.<\/p>\n<p>No din\u00e2mico ecossistema cripto, a integra\u00e7\u00e3o entre finan\u00e7as tradicionais e tecnologia blockchain \u00e9 cada vez mais vista como um passo essencial para destravar novas oportunidades de mercado.<\/p>\n<p>O teste envolve o RYT, token lastreado no ChinaAMC USD Digital Money Market Fund e emitido pela China Asset Management (Hong Kong) Limited. Ali\u00e1s, esta \u00e9 uma das gestoras de ativos mais tradicionais da \u00c1sia.<\/p>\n<p>A iniciativa insere esse ativo regulado no Off-Exchange Settlement (OES) da KuCoin para gest\u00e3o de linhas de cr\u00e9dito, permitindo que o token seja utilizado como garantia em opera\u00e7\u00f5es de trading.<\/p>\n<h2>KuCoin quer criar conex\u00e3o entre Web2 e Web3<\/h2>\n<p>Segundo a KuCoin, o objetivo \u00e9 criar novas aplica\u00e7\u00f5es para tokens lastreados em fundos tradicionais, aproximando ainda mais o ecossistema das <a href=\"https:\/\/www.coinspeaker.com\/pt\/melhores-criptomoedas-para-investir\/\" target=\"_blank\">melhores criptomoedas<\/a> das estruturas reguladas.<\/p>\n<p>Usu\u00e1rios que mantiverem RYT poder\u00e3o n\u00e3o s\u00f3 receber rendimento proveniente do fundo, mas tamb\u00e9m utiliz\u00e1-lo como colateral para alavancar opera\u00e7\u00f5es na plataforma, combinando seguran\u00e7a e versatilidade na gest\u00e3o patrimonial.<\/p>\n<p>O modelo tem mecanismos de compliance s\u00f3lidos, incluindo cust\u00f3dia, administra\u00e7\u00e3o e registro de unidades com condu\u00e7\u00e3o do Standard Chartered Bank em Hong Kong. Trata-se de uma camada adicional de confian\u00e7a e rastreabilidade para investidores.<\/p>\n<h2>Potencial para moldar padr\u00f5es do mercado<\/h2>\n<p>Para BC Wong, CEO da KuCoin, a parceria eleva o n\u00edvel de inova\u00e7\u00e3o da plataforma. Al\u00e9m disso, fornece solu\u00e7\u00f5es seguras e em conformidade regulat\u00f3ria, ajudando usu\u00e1rios a gerenciar seus ativos digitais com mais confian\u00e7a em mercados din\u00e2micos.<\/p>\n<p>J\u00e1 Thomas Zhu, CEO da AlloyX, destacou que o projeto \u00e9 um passo pr\u00e1tico voltado \u00e0 constru\u00e7\u00e3o de cen\u00e1rios e mecanismos de colateral. Ele oferece aos usu\u00e1rios novas possibilidades de utiliza\u00e7\u00e3o de ativos. Ao setor, gera oportunidades de valida\u00e7\u00e3o estrutural.<\/p>\n<p>Especialistas apontam que a ado\u00e7\u00e3o de <a href=\"https:\/\/www.coinspeaker.com\/pt\/mercado-de-tokenizacao-rwa-cresceu-260-no-1o-semestre-de-2025\/\" target=\"_blank\">RWAs<\/a> como colateral em exchanges centralizadas pode ampliar a liquidez do mercado e incentivar a entrada de emissores tradicionais, diversificando o ecossistema.<\/p>\n<p>Os RWAs ainda est\u00e3o em est\u00e1gio inicial de ado\u00e7\u00e3o. No entanto, a uni\u00e3o entre KuCoin e AlloyX mostra como essa classe de ativos pode evoluir de testes isolados para padr\u00f5es amplamente utilizados.<\/p>\n<p>Al\u00e9m disso, a integra\u00e7\u00e3o de produtos financeiros tradicionais no ambiente cripto pode n\u00e3o apenas atrair mais capital institucional, mas tamb\u00e9m servir de refer\u00eancia para reguladores e outras plataformas.<\/p>\n<h2>Snorter Bot: Efici\u00eancia e agilidade na nova era cripto<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2394\" src=\"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/07\/snorter-busca-as-melhores-oportunidades.png\" alt=\"\" width=\"866\" height=\"797\" srcset=\"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/07\/snorter-busca-as-melhores-oportunidades.png 866w, https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/07\/snorter-busca-as-melhores-oportunidades-300x276.png 300w, https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/07\/snorter-busca-as-melhores-oportunidades-768x707.png 768w\" sizes=\"auto, (max-width: 866px) 100vw, 866px\" \/><\/p>\n<p>A integra\u00e7\u00e3o de ativos do mundo real \u00e0s exchanges representa apenas uma das frentes da evolu\u00e7\u00e3o do mercado. Com o mesmo esp\u00edrito de inova\u00e7\u00e3o e efici\u00eancia, o<a rel=\"nofollow sponsored\" href=\"https:\/\/www.coinspeaker.com\/pt\/visit\/snorter-bot\" target=\"_blank\"> Snorter Bot<\/a> vem se destacando como uma solu\u00e7\u00e3o para quem busca maximizar resultados em um cen\u00e1rio din\u00e2mico.<\/p>\n<p>Operando diretamente pelo Telegram, ele permite a execu\u00e7\u00e3o ultrarr\u00e1pida de ordens. Al\u00e9m disso, com o Snorter, voc\u00ea tem acesso a monitoramento em tempo real e prote\u00e7\u00e3o contra golpes comuns em negocia\u00e7\u00f5es de memecoins e altcoins de baixa capitaliza\u00e7\u00e3o.<\/p>\n<p>Assim como os RWAs ampliam a utilidade e a liquidez de ativos tradicionais na blockchain, o <a rel=\"noopener noreferrer\" href=\"https:\/\/snortertoken.com\/pt\" target=\"_blank\">Snorter Bot<\/a> expande as possibilidades de atua\u00e7\u00e3o dos traders.<\/p>\n<p>Ele faz isso oferecendo um ecossistema mais seguro e responsivo. Essas s\u00e3o caracter\u00edsticas essenciais para se posicionar \u00e0 frente em um mercado que n\u00e3o para de evoluir.<\/p>\n<p>Ali\u00e1s, a pr\u00e9-venda do Snorter j\u00e1 levantou mais de US$ 3 milh\u00f5es em pouco mais de dois meses. Com isso, superou a capta\u00e7\u00e3o inicial de bots de refer\u00eancia no mercado, como o Banana Gun.<\/p>\n<p>At\u00e9 o pr\u00f3ximo est\u00e1gio de pre\u00e7o, voc\u00ea pode adquirir $SNORT a US$ 0,1013.<\/p>\n<p>Al\u00e9m de taxas de execu\u00e7\u00e3o mais baixas (0,85%) e recursos como copy trading, prote\u00e7\u00e3o contra MEV e detec\u00e7\u00e3o de honeypots, o token oferece acesso a an\u00e1lises avan\u00e7adas, staking e governan\u00e7a.<\/p>\n<p><strong><a href=\"https:\/\/www.coinspeaker.com\/pt\/visit\/snorter-bot\" target=\"_blank\" rel=\"noopener nofollow sponsored\">Visite a pr\u00e9-venda do Snorter<\/a><\/strong><\/p>\n<p><em><strong>Disclaimer: Coinspeaker est\u00e1 comprometido em fornecer reportagens imparciais e transparentes. Este artigo tem como objetivo fornecer informa\u00e7\u00f5es precisas e oportunas. Mas n\u00e3o deve ser considerado como conselho financeiro ou de investimento. Como as condi\u00e7\u00f5es do mercado podem mudar rapidamente, recomendamos que voc\u00ea verifique as informa\u00e7\u00f5es por conta pr\u00f3pria. E consulte um profissional antes de tomar qualquer decis\u00e3o com base neste conte\u00fado.<\/strong><\/em><\/p>\n<a class=\"infinscroll_next_page_link\" style=\"display:none\" href=\"https:\/\/www.coinspeaker.com\/pt\/cvm-planeja-aumentar-limites-de-tokenizacao-via-crowdfunding\/\" rel=\"prev\">next<\/a>","protected":false},"excerpt":{"rendered":"<p>Uso de RWAs como colateral aproxima cripto e finan\u00e7as tradicionais.<\/p>\n","protected":false},"author":181,"featured_media":3295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[182,314,385],"class_list":["post-3287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain","tag-rwa","tag-snort","tag-snorter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KuCoin e AlloyX avan\u00e7am em integra\u00e7\u00e3o de RWAs como colateral - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas<\/title>\n<meta name=\"description\" content=\"KuCoin e AlloyX iniciam teste para usar tokens de ativos do mundo real (RWAs) como colateral, integrando finan\u00e7as tradicionais e blockchain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KuCoin e AlloyX avan\u00e7am em integra\u00e7\u00e3o de RWAs como colateral - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas\" \/>\n<meta property=\"og:description\" content=\"KuCoin e AlloyX iniciam teste para usar tokens de ativos do mundo real (RWAs) como colateral, integrando finan\u00e7as tradicionais e blockchain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/\" \/>\n<meta property=\"og:site_name\" content=\"Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T21:20:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/08\/kucoin-e-alloyx-lancam-projeto-de-rwa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Gomes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Gomes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KuCoin e AlloyX avan\u00e7am em integra\u00e7\u00e3o de RWAs como colateral - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","description":"KuCoin e AlloyX iniciam teste para usar tokens de ativos do mundo real (RWAs) como colateral, integrando finan\u00e7as tradicionais e blockchain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/","og_locale":"pt_PT","og_type":"article","og_title":"KuCoin e AlloyX avan\u00e7am em integra\u00e7\u00e3o de RWAs como colateral - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","og_description":"KuCoin e AlloyX iniciam teste para usar tokens de ativos do mundo real (RWAs) como colateral, integrando finan\u00e7as tradicionais e blockchain.","og_url":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/","og_site_name":"Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","article_published_time":"2025-08-15T21:20:04+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/08\/kucoin-e-alloyx-lancam-projeto-de-rwa.png","type":"image\/png"}],"author":"Gabriel Gomes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Gomes","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#article","isPartOf":{"@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/"},"author":{"name":"Gabriel Gomes","@id":"https:\/\/www.coinspeaker.com\/pt\/#\/schema\/person\/5d4a1a955d4f8a09ce87376d0b6ca41a"},"headline":"KuCoin e AlloyX avan\u00e7am na integra\u00e7\u00e3o de RWAs com teste de colateral","datePublished":"2025-08-15T21:20:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/"},"wordCount":764,"commentCount":0,"image":{"@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/08\/kucoin-e-alloyx-lancam-projeto-de-rwa.png","keywords":["RWA","SNORT","Snorter"],"articleSection":["Not\u00edcias de Blockchain"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.coinspeaker.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/","url":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/","name":"KuCoin e AlloyX avan\u00e7am em integra\u00e7\u00e3o de RWAs como colateral - Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","isPartOf":{"@id":"https:\/\/www.coinspeaker.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#primaryimage"},"image":{"@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/08\/kucoin-e-alloyx-lancam-projeto-de-rwa.png","datePublished":"2025-08-15T21:20:04+00:00","author":{"@id":"https:\/\/www.coinspeaker.com\/pt\/#\/schema\/person\/5d4a1a955d4f8a09ce87376d0b6ca41a"},"description":"KuCoin e AlloyX iniciam teste para usar tokens de ativos do mundo real (RWAs) como colateral, integrando finan\u00e7as tradicionais e blockchain.","breadcrumb":{"@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#primaryimage","url":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/08\/kucoin-e-alloyx-lancam-projeto-de-rwa.png","contentUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/08\/kucoin-e-alloyx-lancam-projeto-de-rwa.png","width":1200,"height":800,"caption":"kucoin e alloyx lan\u00e7am projeto de rwa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coinspeaker.com\/pt\/kucoin-e-alloyx-avancam-na-integracao-de-rwas-com-teste-de-colateral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.coinspeaker.com\/pt\/"},{"@type":"ListItem","position":2,"name":"KuCoin e AlloyX avan\u00e7am na integra\u00e7\u00e3o de RWAs com teste de colateral"}]},{"@type":"WebSite","@id":"https:\/\/www.coinspeaker.com\/pt\/#website","url":"https:\/\/www.coinspeaker.com\/pt\/","name":"Coinspeaker - Not\u00edcias de criptomoedas em portugu\u00eas","description":"Not\u00edcias de criptomoedas em tempo real! \u00daltimas tend\u00eancias e acontecimentos da blockchain, Bitcoin, Ethereum e Altcoins.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coinspeaker.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.coinspeaker.com\/pt\/#\/schema\/person\/5d4a1a955d4f8a09ce87376d0b6ca41a","name":"Gabriel Gomes","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/cropped-Gabriel-1-96x96.jpg","url":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/cropped-Gabriel-1-96x96.jpg","contentUrl":"https:\/\/www.coinspeaker.com\/pt\/wp-content\/uploads\/sites\/5\/2025\/06\/cropped-Gabriel-1-96x96.jpg","caption":"Gabriel Gomes"},"description":"Com forma\u00e7\u00e3o em TI, Gabriel tem dedicado os \u00faltimos anos em reda\u00e7\u00e3o de conte\u00fado especializado em criptoativos, Web3 e inova\u00e7\u00e3o financeira. Sua intensa curiosidade gera an\u00e1lises, not\u00edcias e artigos opinativos sobre o futuro do dinheiro, com foco em projetos relevantes, tecnologias disruptivas e tend\u00eancias de mercado.","url":"https:\/\/www.coinspeaker.com\/pt\/author\/gabriel\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts\/3287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/comments?post=3287"}],"version-history":[{"count":3,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts\/3287\/revisions"}],"predecessor-version":[{"id":3320,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/posts\/3287\/revisions\/3320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/media\/3295"}],"wp:attachment":[{"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/media?parent=3287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/categories?post=3287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coinspeaker.com\/pt\/wp-json\/wp\/v2\/tags?post=3287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}